{"id":850,"date":"2022-11-12T00:24:52","date_gmt":"2022-11-12T00:24:52","guid":{"rendered":"https:\/\/sparkhost.com.br\/blog\/?p=850"},"modified":"2022-12-20T19:25:05","modified_gmt":"2022-12-20T19:25:05","slug":"como-alterar-o-dominio-principal","status":"publish","type":"post","link":"https:\/\/sparkhost.com.br\/blog\/wordpress\/como-alterar-o-dominio-principal\/","title":{"rendered":"Como alterar o dom\u00ednio principal no WordPress"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<h4>Existem diversos m\u00e9todos de altera\u00e7\u00e3o do dom\u00ednio principal de uma instala\u00e7\u00e3o\u00a0<mark><em><strong>WordPress<\/strong><\/em><\/mark>, nosso time separou as mais f\u00e1cies de alterar, todas ser\u00e3o listadas abaixo com n\u00edvel de facilidade individualmente falando.<\/h4>\n\n\n\n<h4>Mudar URL WordPress pelo wp-admin<\/h4>\n\n\n\n<p>Sem d\u00favidas essa \u00e9 a mais indicada, pela facilidade em alterar o processo, mas antes de fazer isso \u00e9 necess\u00e1rio\u00a0<mark>estacionar o novo dom\u00ednio<\/mark>\u00a0em sua hospedagem, para evitar que voc\u00ea perca acessibilidade da sua instala\u00e7\u00e3o\u00a0<mark>WordPress<\/mark>.<\/p>\n\n\n\n<ol>\n<li>Acesse o seu&nbsp;<strong><mark>wp-admin<\/mark><\/strong>;<\/li>\n\n\n\n<li>Localize o menu&nbsp;<strong><mark>Configura\u00e7\u00f5es gerais<\/mark><\/strong>;<\/li>\n\n\n\n<li>Modifique o dom\u00ednio antigo pelo novo nos campos&nbsp;<strong><mark>Endere\u00e7o do WordPress (URL)&nbsp;e&nbsp;Endere\u00e7o do site (URL)<\/mark><\/strong>;<\/li>\n\n\n\n<li>Feito isso apenas aplique as altera\u00e7\u00f5es clicando em&nbsp;Salvar altera\u00e7\u00f5es;<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"783\" height=\"450\" src=\"https:\/\/sparkhost.com.br\/blog\/wp-content\/uploads\/2022\/11\/imagem_2022-11-11_201922842.png\" alt=\"\" class=\"wp-image-852\" srcset=\"https:\/\/sparkhost.com.br\/blog\/wp-content\/uploads\/2022\/11\/imagem_2022-11-11_201922842.png 783w, https:\/\/sparkhost.com.br\/blog\/wp-content\/uploads\/2022\/11\/imagem_2022-11-11_201922842-300x172.png 300w, https:\/\/sparkhost.com.br\/blog\/wp-content\/uploads\/2022\/11\/imagem_2022-11-11_201922842-768x441.png 768w, https:\/\/sparkhost.com.br\/blog\/wp-content\/uploads\/2022\/11\/imagem_2022-11-11_201922842-360x207.png 360w\" sizes=\"(max-width: 783px) 100vw, 783px\" \/><\/figure>\n\n\n\n<h4>Alterar dom\u00ednio a partir do arquivo&nbsp;wp-config.php<\/h4>\n\n\n\n<p>Alterar o dom\u00ednio a partir do arquivo wp-config.php \u00e9 poss\u00edvel tamb\u00e9m, por\u00e9m recomendar\u00edamos essa altera\u00e7\u00e3o se ela fosse tempor\u00e1ria, por exemplo no aguardo da propaga\u00e7\u00e3o do seu novo dom\u00ednio para c\u00e1. Essa altera\u00e7\u00e3o em alguns processos de atualiza\u00e7\u00e3o de plugins ou at\u00e9 mesmo da instala\u00e7\u00e3o do&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/br.wordpress.org\/\" target=\"_blank\"><mark>Wo<\/mark><\/a><mark>r<\/mark><a rel=\"noreferrer noopener\" href=\"https:\/\/br.wordpress.org\/\" target=\"_blank\"><mark>dPress<\/mark><\/a>&nbsp;pode gerar dores de cabe\u00e7a.&nbsp;<mark>N\u00e3o recomendamos fazer isso em produ\u00e7\u00e3o<\/mark>.<\/p>\n\n\n\n<ol>\n<li>Acesse o&nbsp;cPanel;<\/li>\n\n\n\n<li>V\u00e1 at\u00e9 o&nbsp;Gerenciador de arquivos;<\/li>\n\n\n\n<li>Localize o&nbsp;diret\u00f3rio de instala\u00e7\u00e3o&nbsp;do seu WordPress;<\/li>\n\n\n\n<li>Localize agora o arquivo&nbsp;wp-config.php;<\/li>\n\n\n\n<li>Adicione a seguinte linhas no inicio do arquivo:<\/li>\n<\/ol>\n\n\n\n<pre class=\"wp-block-code\"><code>define('WP_HOME','http:\/\/seu-novo-dom\u00ednio.com');\ndefine('WP_SITEURL','http:\/\/seu-novo-dom\u00ednio.com');\n<\/code><\/pre>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"642\" height=\"399\" src=\"https:\/\/sparkhost.com.br\/blog\/wp-content\/uploads\/2022\/11\/imagem_2022-11-11_202041042.png\" alt=\"\" class=\"wp-image-853\" srcset=\"https:\/\/sparkhost.com.br\/blog\/wp-content\/uploads\/2022\/11\/imagem_2022-11-11_202041042.png 642w, https:\/\/sparkhost.com.br\/blog\/wp-content\/uploads\/2022\/11\/imagem_2022-11-11_202041042-300x186.png 300w, https:\/\/sparkhost.com.br\/blog\/wp-content\/uploads\/2022\/11\/imagem_2022-11-11_202041042-360x224.png 360w\" sizes=\"(max-width: 642px) 100vw, 642px\" \/><\/figure>\n\n\n\n<h4>Atualizar o Banco de Dados<\/h4>\n\n\n\n<p>Alterar o dom\u00ednio atrav\u00e9s do bancos de dados \u00e9 poss\u00edvel, entretanto recomendamos que se atente as altera\u00e7\u00f5es, pois alterar qualquer outra vari\u00e1vel ou mesmo adicionar caracteres que n\u00e3o s\u00e3o necess\u00e1rios podem gerar problemas na sua instala\u00e7\u00e3o&nbsp;<mark>WordPress<\/mark>, por isso recomendamos que fa\u00e7a um backup antes de continuar.<\/p>\n\n\n\n<ol>\n<li>&nbsp;Acesse o&nbsp;cPanel;<\/li>\n\n\n\n<li>Localize a op\u00e7\u00e3o&nbsp;phpMyAdmin;<\/li>\n\n\n\n<li>Localize o&nbsp;bancos de dados da instala\u00e7\u00e3o&nbsp;WordPress;<\/li>\n\n\n\n<li>Em seguida localize a tabela&nbsp;<em>wp_options<\/em>;<\/li>\n\n\n\n<li>Agora \u00e9 s\u00f3 localizar&nbsp;<em>option_id<\/em>&nbsp;1 e 2;<\/li>\n\n\n\n<li>Altere&nbsp;ambos&nbsp;os campos&nbsp;com o&nbsp;novo dom\u00ednio;<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"878\" height=\"191\" src=\"https:\/\/sparkhost.com.br\/blog\/wp-content\/uploads\/2022\/11\/imagem_2022-11-11_202146432.png\" alt=\"\" class=\"wp-image-854\" srcset=\"https:\/\/sparkhost.com.br\/blog\/wp-content\/uploads\/2022\/11\/imagem_2022-11-11_202146432.png 878w, https:\/\/sparkhost.com.br\/blog\/wp-content\/uploads\/2022\/11\/imagem_2022-11-11_202146432-300x65.png 300w, https:\/\/sparkhost.com.br\/blog\/wp-content\/uploads\/2022\/11\/imagem_2022-11-11_202146432-768x167.png 768w, https:\/\/sparkhost.com.br\/blog\/wp-content\/uploads\/2022\/11\/imagem_2022-11-11_202146432-360x78.png 360w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Existem diversos m\u00e9todos de altera\u00e7\u00e3o do dom\u00ednio principal de uma instala\u00e7\u00e3o\u00a0WordPress, nosso time separou as mais f\u00e1cies de alterar, todas ser\u00e3o listadas abaixo com n\u00edvel de facilidade individualmente falando. Mudar URL WordPress pelo wp-admin Sem&#8230;<\/p>\n","protected":false},"author":1,"featured_media":855,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[26],"tags":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sparkhost.com.br\/blog\/wp-json\/wp\/v2\/posts\/850"}],"collection":[{"href":"https:\/\/sparkhost.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sparkhost.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sparkhost.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sparkhost.com.br\/blog\/wp-json\/wp\/v2\/comments?post=850"}],"version-history":[{"count":3,"href":"https:\/\/sparkhost.com.br\/blog\/wp-json\/wp\/v2\/posts\/850\/revisions"}],"predecessor-version":[{"id":893,"href":"https:\/\/sparkhost.com.br\/blog\/wp-json\/wp\/v2\/posts\/850\/revisions\/893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sparkhost.com.br\/blog\/wp-json\/wp\/v2\/media\/855"}],"wp:attachment":[{"href":"https:\/\/sparkhost.com.br\/blog\/wp-json\/wp\/v2\/media?parent=850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sparkhost.com.br\/blog\/wp-json\/wp\/v2\/categories?post=850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sparkhost.com.br\/blog\/wp-json\/wp\/v2\/tags?post=850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}